{"id":9422,"date":"2026-05-12T23:28:08","date_gmt":"2026-05-12T23:28:08","guid":{"rendered":"https:\/\/pasahoy.com.ar\/ph\/?p=9422"},"modified":"2026-05-12T23:28:41","modified_gmt":"2026-05-12T23:28:41","slug":"marcha-universitaria-en-todo-el-pais-pidieron-que-la-corte-suprema-los-acompane-y-no-permita-que-el-gobierno-siga-incumpliendo-la-ley","status":"publish","type":"post","link":"https:\/\/pasahoy.com.ar\/ph\/marcha-universitaria-en-todo-el-pais-pidieron-que-la-corte-suprema-los-acompane-y-no-permita-que-el-gobierno-siga-incumpliendo-la-ley\/","title":{"rendered":"MARCHA UNIVERSITARIA EN TODO EL PA\u00cdS: PIDIERON QUE LA CORTE SUPREMA \u201cLOS ACOMPA\u00d1E\u201d Y \u201cNO PERMITA QUE EL GOBIERNO SIGA INCUMPLIENDO LA LEY\u201d"},"content":{"rendered":"\n<p>Estuvieron presentes los titulares del Consejo Interuniversitario Nacional (CIN): Franco Bartolacci, quien preside la entidad, y Anselmo Torres, el vicepresidente, junto a las distintas federaciones gremiales.<\/p>\n\n\n\n<p>Los miembros de la Federaci\u00f3n Universitaria Argentina (FUA) fue la encargada de leer el documento en el que afirmaron que el poder adquisitivo de las partidas correspondientes a los Gastos de Funcionamiento de las Universidades \u00abno ha superado\u00bb, en ninguno de los meses de la gesti\u00f3n del presidente Javier Milei, \u00abel 64% del que ten\u00eda en enero de 2023\u00bb.<\/p>\n\n\n\n<p>\u00abEl Poder Ejecutivo, en un acto de desprecio institucional sin precedentes, ha decidido alzarse contra los otros dos poderes de la Rep\u00fablica: ignora la Ley de Financiamiento Universitario N\u00b0 27.795 sancionada y ratificada por amplias mayor\u00edas en el Congreso, y desoye los fallos de la Justicia que ordenan su cumplimiento inmediato. Cuando el Gobierno decide qu\u00e9 leyes cumple y qu\u00e9 sentencias acata, lo que se rompe no es solo lo relativo al presupuesto universitario, es el contrato social que nos mantiene libres y en un estado de derecho\u00bb, remarcaron.<\/p>\n\n\n\n<p>En la misma l\u00ednea, indicaron que desde diciembre de 2023 \u00abse ha perdido el equivalente a casi 9 meses de transferencias\u00bb; asimsimo, manifestaron que la crisis que atraviesan las universidades \u00abno es solo presupuestaria\u00bb, porque como ciudadanos \u00abdeben denunciar con dolor y firmeza\u00bb la \u00abruptura del acuerdo democr\u00e1tico\u00bb de la divisi\u00f3n de poderes que tenemos en la naci\u00f3n.<\/p>\n\n\n\n<p>Para finalizar, expresaron que la universidad p\u00fablica y el sistema p\u00fablico de investigaci\u00f3n, \u00abson factores fundamentales de la econom\u00eda del pa\u00eds\u00bb y, adem\u00e1s, funcionan como recursos estrat\u00e9gicos para que la industria nacional pueda \u00abcompetir en el mundo\u00bb y \u00abgenerar puestos de trabajo con derechos, y ambientalmente sustentables\u00bb: \u00abTodo proyecto de pa\u00eds necesita una universidad de excelencia que aporte desde la soberan\u00eda cient\u00edfica, tecnol\u00f3gica y de las artes a su desarrollo\u00bb, a\u00f1adieron.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"811\" height=\"540\" data-id=\"9423\" src=\"https:\/\/pasahoy.com.ar\/ph\/wp-content\/uploads\/2026\/05\/1001363015.jpg\" alt=\"\" class=\"wp-image-9423\" srcset=\"https:\/\/pasahoy.com.ar\/ph\/wp-content\/uploads\/2026\/05\/1001363015.jpg 811w, https:\/\/pasahoy.com.ar\/ph\/wp-content\/uploads\/2026\/05\/1001363015-300x200.jpg 300w, https:\/\/pasahoy.com.ar\/ph\/wp-content\/uploads\/2026\/05\/1001363015-768x511.jpg 768w\" sizes=\"auto, (max-width: 811px) 100vw, 811px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Estuvieron presentes los titulares del Consejo Interuniversitario Nacional (CIN): Franco Bartolacci, quien preside la entidad, y Anselmo Torres, el vicepresidente, junto a las distintas federaciones gremiales. Los miembros de la Federaci\u00f3n Universitaria Argentina (FUA) fue la encargada de leer el documento en el que afirmaron que el poder adquisitivo de las partidas correspondientes a los [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":9423,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-9422","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"jetpack_featured_media_url":"https:\/\/pasahoy.com.ar\/ph\/wp-content\/uploads\/2026\/05\/1001363015.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pasahoy.com.ar\/ph\/wp-json\/wp\/v2\/posts\/9422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pasahoy.com.ar\/ph\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pasahoy.com.ar\/ph\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pasahoy.com.ar\/ph\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/pasahoy.com.ar\/ph\/wp-json\/wp\/v2\/comments?post=9422"}],"version-history":[{"count":1,"href":"https:\/\/pasahoy.com.ar\/ph\/wp-json\/wp\/v2\/posts\/9422\/revisions"}],"predecessor-version":[{"id":9424,"href":"https:\/\/pasahoy.com.ar\/ph\/wp-json\/wp\/v2\/posts\/9422\/revisions\/9424"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pasahoy.com.ar\/ph\/wp-json\/wp\/v2\/media\/9423"}],"wp:attachment":[{"href":"https:\/\/pasahoy.com.ar\/ph\/wp-json\/wp\/v2\/media?parent=9422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pasahoy.com.ar\/ph\/wp-json\/wp\/v2\/categories?post=9422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pasahoy.com.ar\/ph\/wp-json\/wp\/v2\/tags?post=9422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}